{"id":2,"date":"2023-01-31T08:25:22","date_gmt":"2023-01-31T07:25:22","guid":{"rendered":"http:\/\/29-26.com\/?page_id=2"},"modified":"2023-10-02T15:54:19","modified_gmt":"2023-10-02T13:54:19","slug":"page-d-exemple","status":"publish","type":"page","link":"https:\/\/29-26.com\/","title":{"rendered":"Accueil"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbHeader\u00a0\u00bb _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb use_background_color_gradient=\u00a0\u00bbon\u00a0\u00bb background_color_gradient_stops=\u00a0\u00bbrgba(10,0,0,0) 0%|rgba(38,16,4,0.95) 100%\u00a0\u00bb background_color_gradient_overlays_image=\u00a0\u00bbon\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/29-26.com\/wp-content\/uploads\/2023\/10\/Design-sans-titre-1.png\u00a0\u00bb custom_padding=\u00a0\u00bb6vw||6vw||true|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; locked=\u00a0\u00bboff\u00a0\u00bb collapsed=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb alt=\u00a0\u00bbtexture laiton\u00a0\u00bb title_text=\u00a0\u00bbtexture laiton\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;][et_pb_row _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb700px\u00a0\u00bb width_tablet=\u00a0\u00bb80%\u00a0\u00bb width_phone=\u00a0\u00bb80%\u00a0\u00bb width_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/29-26.com\/wp-content\/uploads\/2023\/03\/2926.png\u00a0\u00bb alt=\u00a0\u00bb2926 logo blanc\u00a0\u00bb title_text=\u00a0\u00bb2926&Prime; _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb45%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbc16985e1-e0d6-4022-964d-e2bfc04fa633&Prime; text_font_size=\u00a0\u00bb11px\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_line_height=\u00a0\u00bb1.2em\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb40px\u00a0\u00bb header_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1><span style=\"font-weight: 400;\">Artisan Sculpteur Designer &#8211; Toulouse (France)<\/span><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbProducts\u00a0\u00bb _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_enable_color=\u00a0\u00bboff\u00a0\u00bb custom_padding=\u00a0\u00bb17px||3px|||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb collapsed=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbb327cbe4-b1d5-4b66-ad37-40c8f2f061ba\u00a0\u00bb header_font=\u00a0\u00bbJost||||||||\u00a0\u00bb header_2_font=\u00a0\u00bbJost|600|||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#000000&Prime; header_2_font_size=\u00a0\u00bb36px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.2em\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb32px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2><span class=\"S1PPyQ\" style=\"font-size: x-large;\">Atelier d&rsquo;Art et Design d\u2019int\u00e9rieur : Mobilier, luminaires &amp; d\u00e9co d\u2019art sur-mesure <br \/><\/span><\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><span>Vous r\u00eavez d\u2019acqu\u00e9rir une pi\u00e8ce d\u2019art contemporaine unique ou sur-mesure ? Un meuble ou un objet aux lignes \u00e9pur\u00e9es qui apportera une touche design et singuli\u00e8re \u00e0 votre int\u00e9rieur ? Avec 29\/26, offrez-vous une oeuvre 100% personnalis\u00e9e et r\u00e9alis\u00e9e \u00e0 la main par notre atelier Toulousain dans le sud de la France. <\/span><span>Nous cr\u00e9ons pour vous des pi\u00e8ces uniques qui sublimeront votre int\u00e9rieur ! <\/span>Invitez l&rsquo;art et la singularit\u00e9 dans votre salon !<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_4,1_4,1_4,1_4&Prime; _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bbnone\u00a0\u00bb custom_margin=\u00a0\u00bb46px|auto||auto||\u00a0\u00bb custom_padding=\u00a0\u00bb13px|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/29-26.com\/wp-content\/uploads\/2023\/03\/lampe1-min.png\u00a0\u00bb title_text=\u00a0\u00bblampe1-min\u00a0\u00bb _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||20px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Morgane &#8211; Lampe Design<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/29-26.com\/wp-content\/uploads\/2023\/03\/d51115d4d2e6488f86046a5496b1e3c2.webp\u00a0\u00bb title_text=\u00a0\u00bbd51115d4d2e6488f86046a5496b1e3c2&Prime; _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||20px||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Stella &#8211; Lampe de table<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/29-26.com\/wp-content\/uploads\/2023\/03\/pot-de-fleurs-min.png\u00a0\u00bb alt=\u00a0\u00bbporte pot laiton\u00a0\u00bb title_text=\u00a0\u00bbpot de fleurs-min\u00a0\u00bb _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||20px||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Amber &#8211;\u00a0 Cache pot design<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/29-26.com\/wp-content\/uploads\/2023\/03\/999b90277bcc4301b74fedcf10a4d26c.webp\u00a0\u00bb alt=\u00a0\u00bblumi\u00e8re lampe cuivre luminaire\u00a0\u00bb title_text=\u00a0\u00bb999b90277bcc4301b74fedcf10a4d26c\u00a0\u00bb _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||20px||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Hector &#8211; Lampe de chevet<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbCall to Action\u00a0\u00bb _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#f4f4f4&Prime; collapsed=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_3_font=\u00a0\u00bbJost|700|||||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#b36700&Prime; header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 class=\"title_bloc_animation\">Des pi\u00e8ces uniques<\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bb1f09816e-184e-4ce5-a4cf-b39c52c423ca\u00a0\u00bb text_font=\u00a0\u00bbOpen Sans||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#666666&Prime; text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_line_height=\u00a0\u00bb1.8em\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb15px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb14px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb55px\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>En tant qu&rsquo;artisan designer de mobilier et d&rsquo;objet d&rsquo;art haut de gamme, Antoine Bieysse de l&rsquo;Atelier 29\/26 cr\u00e9e des pi\u00e8ces uniques mais aussi sur mesure en fonction des demandes sp\u00e9cifiques de ses clients.\u00a0<\/p>\n<p>Il travaille principalement avec des m\u00e9taux tels que l&rsquo;acier, le cuivre, l&rsquo;aluminum et le laiton pour cr\u00e9er des meubles, des sculptures, des lampes et des objets d\u00e9coratifs qui sont \u00e0 la fois fonctionnels et esth\u00e9tiquement attrayants. Antoine utilise une combinaison de techniques traditionnelles et modernes pour cr\u00e9er des pi\u00e8ces qui sont durables et de qualit\u00e9 sup\u00e9rieure.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/29-26.com\/wp-content\/uploads\/2023\/03\/luminaire-2-min-e1678384230763.png\u00a0\u00bb alt=\u00a0\u00bbluminaire plafonnier \u00a0\u00bb title_text=\u00a0\u00bbluminaire 2-min\u00a0\u00bb _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbCall to Action\u00a0\u00bb _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_enable_color=\u00a0\u00bboff\u00a0\u00bb collapsed=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/29-26.com\/wp-content\/uploads\/2023\/03\/luminaire-3-min.png\u00a0\u00bb alt=\u00a0\u00bbluminaire plafonnier \u00a0\u00bb title_text=\u00a0\u00bbluminaire 3-min\u00a0\u00bb _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb89%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font=\u00a0\u00bbJost||||||||\u00a0\u00bb header_3_font=\u00a0\u00bbJost|700|||||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#b36700&Prime; header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 class=\"title_bloc_animation\">Un savoir-faire fran\u00e7ais &amp; artisanal<\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bb1f09816e-184e-4ce5-a4cf-b39c52c423ca\u00a0\u00bb text_font=\u00a0\u00bbOpen Sans||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#666666&Prime; text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_line_height=\u00a0\u00bb1.8em\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; text_font_size_tablet=\u00a0\u00bb15px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb14px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb55px\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<p>Dans l&rsquo;atelier 29\/26 situ\u00e9 dans le sud de la France, la fabrication traditionnelle et la modernite\u0301 sont comple\u0301mentaires.<\/p>\n<p>Nous concevons des mod\u00e8les, s\u00e9lectionnons les mat\u00e9riaux, fabriquons les pi\u00e8ces \u00e0 la main ou \u00e0 l&rsquo;aide d&rsquo;outils et de machines sp\u00e9cialis\u00e9es. Nous nous occupons \u00e9galement de la finition pour obtenir un rendu parfait.<\/p>\n<p>Nous pouvons \u00e9galement travailler en \u00e9troite collaboration avec d&rsquo;autres artisans et artistes tels que des marbriers ou menuisiers \u00e9b\u00e9nistes pour cr\u00e9er des pi\u00e8ces personnalis\u00e9es qui r\u00e9pondent \u00e0 vos besoins et envies.<\/p>\n<p>Notre travail t\u00e9moignage de notre passion pour la cr\u00e9ation de meubles et d&rsquo;objets qui sont \u00e0 la fois fonctionnels et esth\u00e9tiquement attrayants.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#000000&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/29-26.com\/wp-content\/uploads\/2023\/03\/pexels-danial-abdullah-2480481-min-scaled.jpg\u00a0\u00bb alt=\u00a0\u00bbsoudure soudeur metal\u00a0\u00bb title_text=\u00a0\u00bbsoudure soudeur metal\u00a0\u00bb _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb filter_saturate=\u00a0\u00bb0%\u00a0\u00bb filter_brightness=\u00a0\u00bb147%\u00a0\u00bb filter_contrast=\u00a0\u00bb114%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbb327cbe4-b1d5-4b66-ad37-40c8f2f061ba\u00a0\u00bb header_2_font=\u00a0\u00bbJost|600|||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_2_font_size=\u00a0\u00bb48px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.2em\u00a0\u00bb header_3_font=\u00a0\u00bbJost||||||||\u00a0\u00bb header_4_font=\u00a0\u00bbJost|600|||||||\u00a0\u00bb header_4_font_size=\u00a0\u00bb34px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb custom_padding=\u00a0\u00bb17px||8px|||\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb32px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h4><span style=\"font-size: xx-large;\"><strong><span style=\"color: #ffffff;\">\u00c0 propos<\/span><\/strong><\/span><\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bb1f09816e-184e-4ce5-a4cf-b39c52c423ca\u00a0\u00bb text_font=\u00a0\u00bbOpen Sans||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_line_height=\u00a0\u00bb1.8em\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||30px||false|false\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb15px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb14px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb55px\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>\u00a0\u00ab\u00a0Je suis passionn\u00e9 par mon m\u00e9tier et je m&rsquo;efforce de cr\u00e9er des pi\u00e8ces qui refl\u00e8tent la personnalit\u00e9 et les go\u00fbts de mes clients.<\/p>\n<p>Je travaille principalement avec des m\u00e9taux tels que l&rsquo;acier, le cuivre, l\u2019aluminum et le laiton pour cr\u00e9er des meubles, des sculptures, des lampes et des objets d\u00e9coratifs qui sont \u00e0 la fois fonctionnels et esth\u00e9tiquement attrayants. J&rsquo;utilise une combinaison de techniques traditionnelles et modernes pour cr\u00e9er des pi\u00e8ces qui sont durables et de qualit\u00e9 sup\u00e9rieure.<\/p>\n<p>Je suis toujours \u00e0 l&rsquo;\u00e9coute pour comprendre les besoins de mes clients et leurs pr\u00e9f\u00e9rences. Je peux travailler avec eux pour concevoir et r\u00e9aliser des pi\u00e8ces uniques qui s&rsquo;int\u00e8grent parfaitement dans leur environnement de vie ou de travail.\u00a0\u00bb<\/p>\n<p>Antoine Bieysse<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbFeature\u00a0\u00bb _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#f4f4f4&Prime; custom_margin=\u00a0\u00bb-1px|||||\u00a0\u00bb custom_padding=\u00a0\u00bb27px|||||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb collapsed=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; use_custom_gutter=\u00a0\u00bbon\u00a0\u00bb gutter_width=\u00a0\u00bb2&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb|40px|80px|40px|false|true\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb|30px|30px|30px|false|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb|20px|20px|20px|false|true\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb border_width_all=\u00a0\u00bb4px\u00a0\u00bb border_color_all=\u00a0\u00bb#0A0A0A\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbe6504a1b-67eb-4b3d-b023-bcab277610b6&Prime; text_font=\u00a0\u00bbInter|700||on|||||\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_letter_spacing=\u00a0\u00bb3px\u00a0\u00bb header_4_font=\u00a0\u00bbInter|700||on|||||\u00a0\u00bb header_4_text_color=\u00a0\u00bbrgba(0,0,0,0.62)\u00a0\u00bb header_4_font_size=\u00a0\u00bb14px\u00a0\u00bb header_4_letter_spacing=\u00a0\u00bb0.3em\u00a0\u00bb header_4_line_height=\u00a0\u00bb1.4em\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb width=\u00a0\u00bb65%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb-10px||60px||false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb-10px||30px||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb-10px||30px||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_padding=\u00a0\u00bb|3%||3%|false|true\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>O\u00f9 me retrouver ?<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbb327cbe4-b1d5-4b66-ad37-40c8f2f061ba\u00a0\u00bb header_2_font=\u00a0\u00bbJost|600|||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#000000&Prime; header_2_font_size=\u00a0\u00bb48px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.2em\u00a0\u00bb header_4_font=\u00a0\u00bbJost|600|||||||\u00a0\u00bb header_4_font_size=\u00a0\u00bb64px\u00a0\u00bb header_4_letter_spacing=\u00a0\u00bb23px\u00a0\u00bb header_5_font=\u00a0\u00bbJost|600|||||||\u00a0\u00bb header_5_font_size=\u00a0\u00bb49px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb32px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h5>Retrouvez mes cr\u00e9ations en galerie d&rsquo;art<\/h5>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bb1f09816e-184e-4ce5-a4cf-b39c52c423ca\u00a0\u00bb text_font=\u00a0\u00bbOpen Sans||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#666666&Prime; text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_line_height=\u00a0\u00bb1.8em\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb15px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb14px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb55px\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Retrouvez mes cr\u00e9ations en galerie d&rsquo;art \/ Concept Store et boutiques sp\u00e9cialis\u00e9es<\/p>\n<p>[\/et_pb_text][et_pb_button button_text=\u00a0\u00bbVoir les localisations\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdb46e67d-9505-40bb-9ebd-8901bc8b3a95&Prime; custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb14px\u00a0\u00bb button_text_color=\u00a0\u00bb#000000&Prime; button_bg_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb button_border_radius=\u00a0\u00bb0px\u00a0\u00bb button_font=\u00a0\u00bbInter|700||on|||||\u00a0\u00bb custom_padding=\u00a0\u00bb16px|24px|16px|24px|true|true\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/29-26.com\/wp-content\/uploads\/2023\/03\/lampe2-min.png\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_divider show_divider=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb height_tablet=\u00a0\u00bb40vw\u00a0\u00bb height_phone=\u00a0\u00bb40vw\u00a0\u00bb height_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbContact Form\u00a0\u00bb _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_enable_color=\u00a0\u00bboff\u00a0\u00bb custom_padding=\u00a0\u00bb38px||9px|||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb collapsed=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb900px\u00a0\u00bb custom_padding=\u00a0\u00bb|30px|50px|30px|false|true\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb||||false|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb|20px|20px|20px|false|true\u00a0\u00bb border_color_all=\u00a0\u00bb#FF6A00&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_6_font=\u00a0\u00bbJost|600|||||||\u00a0\u00bb header_6_font_size=\u00a0\u00bb41px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h6>Contact :<\/h6>\n<p>[\/et_pb_text][et_pb_contact_form captcha=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bb5f451234-b662-41cf-8ad7-48c40d2afa7f\u00a0\u00bb _unique_id=\u00a0\u00bb37352547-b97b-4413-85e2-b00056b20234&Prime; form_field_background_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb form_field_text_color=\u00a0\u00bb#0A0A0A\u00a0\u00bb form_field_custom_padding=\u00a0\u00bb16px|18px|16px|18px|true|true\u00a0\u00bb form_field_font=\u00a0\u00bbInter|700||on|||||\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb14px\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_color=\u00a0\u00bb#0A0A0A\u00a0\u00bb button_border_color=\u00a0\u00bb#0A0A0A\u00a0\u00bb button_border_radius=\u00a0\u00bb0px\u00a0\u00bb button_font=\u00a0\u00bbInter|700||on|||||\u00a0\u00bb button_custom_padding=\u00a0\u00bb16px|24px|16px|24px|true|true\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb border_width_all=\u00a0\u00bb2px\u00a0\u00bb border_color_all=\u00a0\u00bb#0A0A0A\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_contact_field field_id=\u00a0\u00bbName\u00a0\u00bb field_title=\u00a0\u00bbName\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbEmail\u00a0\u00bb field_title=\u00a0\u00bbEmail Address\u00a0\u00bb field_type=\u00a0\u00bbemail\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbMessage\u00a0\u00bb field_title=\u00a0\u00bbMessage\u00a0\u00bb field_type=\u00a0\u00bbtext\u00a0\u00bb fullwidth_field=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb][\/et_pb_contact_field][\/et_pb_contact_form][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Artisan Sculpteur Designer &#8211; Toulouse (France)Atelier d&rsquo;Art et Design d\u2019int\u00e9rieur : Mobilier, luminaires &amp; d\u00e9co d\u2019art sur-mesure Vous r\u00eavez d\u2019acqu\u00e9rir une pi\u00e8ce d\u2019art contemporaine unique ou sur-mesure ? Un meuble ou un objet aux lignes \u00e9pur\u00e9es qui apportera une touche design et singuli\u00e8re \u00e0 votre int\u00e9rieur ? Avec 29\/26, offrez-vous une oeuvre 100% personnalis\u00e9e et [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:paragraph -->\n<p>Ceci est une page d\u2019exemple. C\u2019est diff\u00e9rent d\u2019un article de blog parce qu\u2019elle restera au m\u00eame endroit et appara\u00eetra dans la navigation de votre site (dans la plupart des th\u00e8mes). La plupart des gens commencent par une page \u00ab&nbsp;\u00c0 propos&nbsp;\u00bb qui les pr\u00e9sente aux personnes visitant le site. Cela pourrait ressembler \u00e0 quelque chose comme cela&nbsp;:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>Bonjour&nbsp;! Je suis un m\u00e9canicien qui aspire \u00e0 devenir acteur, et voici mon site. J\u2019habite \u00e0 Bordeaux, j\u2019ai un super chien baptis\u00e9 Russell, et j\u2019aime la vodka (ainsi qu\u2019\u00eatre surpris par la pluie soudaine lors de longues balades sur la plage au coucher du soleil).<\/p>\n<!-- \/wp:paragraph --><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:paragraph -->\n<p>\u2026ou quelque chose comme cela&nbsp;:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>La soci\u00e9t\u00e9 123 Machin Truc a \u00e9t\u00e9 cr\u00e9\u00e9e en 1971, et n\u2019a cess\u00e9 de proposer au public des machins-trucs de qualit\u00e9 depuis lors. Situ\u00e9e \u00e0 Saint-Remy-en-Bouzemont-Saint-Genest-et-Isson, 123 Machin Truc emploie 2 000 personnes, et fabrique toutes sortes de bidules supers pour la communaut\u00e9 bouzemontoise.<\/p>\n<!-- \/wp:paragraph --><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:paragraph -->\n<p>En tant que nouvel utilisateur ou utilisatrice de WordPress, vous devriez vous rendre sur <a href=\"http:\/\/29-26.com\/wp-admin\/\">votre tableau de bord<\/a> pour supprimer cette page et cr\u00e9er de nouvelles pages pour votre contenu. Amusez-vous bien&nbsp;!<\/p>\n<!-- \/wp:paragraph -->","_et_gb_content_width":"","footnotes":""},"class_list":["post-2","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/29-26.com\/index.php\/wp-json\/wp\/v2\/pages\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/29-26.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/29-26.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/29-26.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/29-26.com\/index.php\/wp-json\/wp\/v2\/comments?post=2"}],"version-history":[{"count":47,"href":"https:\/\/29-26.com\/index.php\/wp-json\/wp\/v2\/pages\/2\/revisions"}],"predecessor-version":[{"id":219,"href":"https:\/\/29-26.com\/index.php\/wp-json\/wp\/v2\/pages\/2\/revisions\/219"}],"wp:attachment":[{"href":"https:\/\/29-26.com\/index.php\/wp-json\/wp\/v2\/media?parent=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}